{"id":1864,"date":"2024-03-13T15:01:41","date_gmt":"2024-03-13T21:01:41","guid":{"rendered":"https:\/\/intecap.edu.gt\/certificacionlaboral\/?page_id=1864"},"modified":"2026-03-23T12:39:43","modified_gmt":"2026-03-23T18:39:43","slug":"instalador-de-andamios-de-grapa-y-tubo","status":"publish","type":"page","link":"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalador-de-andamios-de-grapa-y-tubo\/","title":{"rendered":"Instalador de andamios de grapa y tubo"},"content":{"rendered":"<p><div class=\"et_d4_element et_pb_section et_pb_section_0  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_0  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_0  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_0  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h1 style=\"text-align: left;\">CERTIFICACI\u00d3N FUNCIONAL<\/h1><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_row et_pb_row_1 et_pb_gutters3  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_1  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_post_title et_pb_post_title_0 et_pb_bg_layout_light  et_pb_text_align_left\"   >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_title_container\">\n\t\t\t\t\t<h1 class=\"entry-title\"><\/h1>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_d4_element et_pb_section et_pb_section_1  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_2 et_pb_equal_columns  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_2  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_1  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h5 style=\"text-align: justify;\"><strong>Objetivo de la certificaci\u00f3n<\/strong> <br \/>Evaluar y reconocer la experiencia de las personas que se dedican a la instalaci\u00f3n, montaje, modificaci\u00f3n y desmontaje de andamios de grapa y tubo para la ejecuci\u00f3n de trabajos de altura, trabajando para una organizaci\u00f3n o por cuenta propia. <\/h5>\n<h5 style=\"text-align: justify;\"><strong>Requisitos para solicitar la certificaci\u00f3n<\/strong><br \/>1. Ser mayor de 18 a\u00f1os <br \/>\u2022 Presentar copia de documento de identificaci\u00f3n personal vigente<br \/>2. Saber leer y escribir <br \/>3. 1 a\u00f1o (o m\u00e1s) de experiencia prestando servicios como instalador de andamios de grapa y tubo <br \/>\u2022 Presentar copia de constancias laborales <br \/>\u2022 Si no puede presentar constancias, el Intecap realiza una entrevista<br \/>4. Realizar pago del proceso por Q600.00<br \/>\u2022 Despu\u00e9s de revisar sus documentos, el Intecap le indicar\u00e1 el medio y forma para realizar el pago<br \/>\u2022 El pago incluye la evaluaci\u00f3n y la emisi\u00f3n del certificado (si aprueba)<\/h5>\n<h5 style=\"text-align: justify;\"><strong>Proceso de evaluaci\u00f3n<\/strong> <br \/>1. Evaluaci\u00f3n de conocimientos <br \/>\u2022 Examen escrito con preguntas sobre temas relacionados con la especialidad<br \/>\u2022 Tiempo para completar la evaluaci\u00f3n: 50 minutos<\/h5>\n<h5 style=\"text-align: justify;\">2. Evaluaci\u00f3n pr\u00e1ctica<br \/>\u2022 Ejercicio pr\u00e1ctico en el cual el candidato completa las siguientes actividades:<br \/>\u2022 Preparar las condiciones para la instalaci\u00f3n de andamios de grapa y tubo, de acuerdo a requerimientos de obra y especificaciones t\u00e9cnicas<br \/>\u2022 Instalar y desinstalar andamios de grapa y tubo de acuerdo con el plan de trabajo, requerimientos en obra, procedimientos establecidos y seguridad ocupacional<br \/>\u2022 Tiempo para completar la evaluaci\u00f3n: 05 horas con 10 minutos<\/h5>\n<h5 style=\"text-align: justify;\">La informaci\u00f3n detallada se encuentra disponible en el esquema de certificaci\u00f3n correspondiente, disponible en el siguiente enlace:<\/h5><\/div>\n\t\t\t<\/div><div class=\"et_pb_button_module_wrapper et_pb_button_0_wrapper  et_pb_module \">\n\t\t\t\t<a class=\"et_pb_button et_d4_element et_pb_button_0 et_pb_bg_layout_light et_block_module\" href=\"https:\/\/www.intecap.edu.gt\/certificacionlaboral\/esquemas\/funcional\/Esquema%20de%20certificacion%20-%20Instalador%20de%20andamios%20de%20grapa%20y%20tubo.pdf\" target=\"_blank\">Descargar Esquema de Certificaci\u00f3n<\/a>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_divider et_pb_divider_0 et_pb_space\"><div class=\"et_pb_divider_internal\"><\/div><\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_2  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2>EST\u00c1NDARES DISPONIBLES \u2013 CERTIFICACI\u00d3N FUNCIONAL<\/h2><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_3  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><div class=\"pt-cv-wrapper et_smooth_scroll_disabled\"><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys\" id=\"pt-cv-view-ed799c5705\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"6\"><div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/acarreo-madera-animales\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2023\/08\/estibador-madera-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/acarreo-madera-animales\/\" class=\"_self\" target=\"_self\" >Acarreo de madera con animales<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/acarreo-madera-maquinaria\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2026\/03\/acarreo-madera-maq-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/acarreo-madera-maquinaria\/\" class=\"_self\" target=\"_self\" >Acarreo de madera con maquinaria forestal<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/albanil-de-obra-blanca\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2026\/05\/albanil-obrab-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/albanil-de-obra-blanca\/\" class=\"_self\" target=\"_self\" >Alba\u00f1il de obra blanca<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/albanil-de-obra-gris\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2026\/05\/albanil-obrag-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/albanil-de-obra-gris\/\" class=\"_self\" target=\"_self\" >Alba\u00f1il de obra gris<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/analista-de-control-microbiologico-de-los-alimentos\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2024\/03\/analista-control-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/analista-de-control-microbiologico-de-los-alimentos\/\" class=\"_self\" target=\"_self\" >Analista de control microbiol\u00f3gico de los alimentos<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/aplicacion-de-pinturas-en-edificaciones-domiciliares-y-comerciales\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2024\/03\/aplicacion-pinturas-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/aplicacion-de-pinturas-en-edificaciones-domiciliares-y-comerciales\/\" class=\"_self\" target=\"_self\" >Aplicaci\u00f3n de pinturas en edificaciones domiciliares y comerciales<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/aplicacion-extraurbano\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2025\/04\/conductor-bus-extraurbano-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/aplicacion-extraurbano\/\" class=\"_self\" target=\"_self\" >Aplicaci\u00f3n de T\u00e9cnicas de Manejo en Simulador para la Conducci\u00f3n de Bus Extraurbano<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/aplicacionbusurbano\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2019\/10\/aplicacion-urbano-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/aplicacionbusurbano\/\" class=\"_self\" target=\"_self\" >Aplicaci\u00f3n de T\u00e9cnicas de Manejo en Simulador para la Conducci\u00f3n de Bus Urbano<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/aplicacion-bus-articulado\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2019\/10\/aplicacion-urbano-artic-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/aplicacion-bus-articulado\/\" class=\"_self\" target=\"_self\" >Aplicaci\u00f3n de T\u00e9cnicas de Manejo en Simulador para la Conducci\u00f3n de Bus Urbano Articulado<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/aplicacion-plataforma-multi\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2019\/10\/aplicacion-multi-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/aplicacion-plataforma-multi\/\" class=\"_self\" target=\"_self\" >Aplicaci\u00f3n de T\u00e9cnicas de Manejo en Simulador para la Conducci\u00f3n de Cabezal con Plataforma Multifuncional<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/manejo-simulador\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2023\/04\/simulador-microbus-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/manejo-simulador\/\" class=\"_self\" target=\"_self\" >Aplicaci\u00f3n de t\u00e9cnicas de manejo en simulador para la conducci\u00f3n de microb\u00fas, pickup y cami\u00f3n de hasta 3.5 tn<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/conduccion-motocicleta\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2025\/03\/aplicacion-tecnicas-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/conduccion-motocicleta\/\" class=\"_self\" target=\"_self\" >Aplicaci\u00f3n de t\u00e9cnicas para la conducci\u00f3n de motocicletas en simulador de conducci\u00f3n<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/aplicacion-tratamientos-aparato\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2023\/04\/tratamiento-facial-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/aplicacion-tratamientos-aparato\/\" class=\"_self\" target=\"_self\" >Aplicaci\u00f3n de tratamientos faciales con aparatolog\u00eda<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/aplicador-repellos\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2023\/05\/aplicador-repello-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/aplicador-repellos\/\" class=\"_self\" target=\"_self\" >Aplicador de acabados cementicios en edificaciones<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/aplicador-de-acabados-en-madera\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2026\/04\/aplicador-acab-mad-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/aplicador-de-acabados-en-madera\/\" class=\"_self\" target=\"_self\" >Aplicador de acabados en madera<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/aplicador-de-agroquimicos\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2024\/03\/aplicacion-agroq-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/aplicador-de-agroquimicos\/\" class=\"_self\" target=\"_self\" >Aplicador de agroqu\u00edmicos<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/auditor-interno-de-cumplimiento-social-para-vestuarios-y-textiles\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2026\/05\/auditor-vest-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/auditor-interno-de-cumplimiento-social-para-vestuarios-y-textiles\/\" class=\"_self\" target=\"_self\" >Auditor interno de cumplimiento social para vestuarios y textiles<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/barbero-presencial\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2023\/04\/barbero-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/barbero-presencial\/\" class=\"_self\" target=\"_self\" >Barbero (modalidad presencial)<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/barbero-enlinea\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2023\/04\/barbero-1-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/barbero-enlinea\/\" class=\"_self\" target=\"_self\" >Barbero (modalidad virtual\/en l\u00ednea)<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/barista\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2025\/03\/barista-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/barista\/\" class=\"_self\" target=\"_self\" >Barista<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/buenas-practicas\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2023\/04\/cosecha-hortalizas1-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/buenas-practicas\/\" class=\"_self\" target=\"_self\" >Buenas pr\u00e1cticas agr\u00edcolas para la cosecha de frutas y hortalizas<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/buenaspracticas-post\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2023\/04\/cosecha-hortalizas-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/buenaspracticas-post\/\" class=\"_self\" target=\"_self\" >Buenas pr\u00e1cticas de manufactura para la postcosecha de frutas y hortalizas<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/buenas-practicas-refrigeracion\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2023\/04\/refigerante-carga-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/buenas-practicas-refrigeracion\/\" class=\"_self\" target=\"_self\" >Buenas pr\u00e1cticas para la recuperaci\u00f3n y carga de refrigerantes en los sistemas de refrigeraci\u00f3n y aire acondicionado<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/camarera-o\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2023\/04\/camarera-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/camarera-o\/\" class=\"_self\" target=\"_self\" >Camarera\/o<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/carpintero-de-banco\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2026\/04\/carpintero-banco-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/carpintero-de-banco\/\" class=\"_self\" target=\"_self\" >Carpintero de banco<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/cocinero-platillos\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2023\/04\/platillo-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/cocinero-platillos\/\" class=\"_self\" target=\"_self\" >Cocinero de platillos cotidianos<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/constructor-de-cimentaciones-para-edificaciones\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2026\/05\/constructor-cimentaciones-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/constructor-de-cimentaciones-para-edificaciones\/\" class=\"_self\" target=\"_self\" >Constructor de cimentaciones para edificaciones<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/constructor-concreto\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2023\/05\/constructor-concreto-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/constructor-concreto\/\" class=\"_self\" target=\"_self\" >Constructor de Estructuras de Concreto con Acero Reforzado<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/constructor-de-losas-para-edificaciones\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2026\/05\/constructor-lozas-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/constructor-de-losas-para-edificaciones\/\" class=\"_self\" target=\"_self\" >Constructor de losas para edificaciones<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/constructor-de-obra-liviana\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2026\/05\/constructor-obraliv-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/constructor-de-obra-liviana\/\" class=\"_self\" target=\"_self\" >Constructor de obra liviana<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/cubicador\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2023\/07\/cubicacion-productos-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/cubicador\/\" class=\"_self\" target=\"_self\" >Cubicador de Productos Forestales<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/diseno-cejas\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2023\/04\/disenocejas-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/diseno-cejas\/\" class=\"_self\" target=\"_self\" >Dise\u00f1o de cejas con henna y extensi\u00f3n de pesta\u00f1as<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/drenaje-linfatico\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2023\/04\/linfatico-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/drenaje-linfatico\/\" class=\"_self\" target=\"_self\" >Drenaje Linf\u00e1tico<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/escultor-de-unas-acrilicas\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2019\/10\/escultor-unas-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/escultor-de-unas-acrilicas\/\" class=\"_self\" target=\"_self\" >Escultor de U\u00f1as Acr\u00edlicas<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/escultorunas-enlinea\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2019\/10\/escultor-unas-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/escultorunas-enlinea\/\" class=\"_self\" target=\"_self\" >Escultor de U\u00f1as Acr\u00edlicas (En L\u00ednea)<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/estibador-portuario\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2026\/05\/estibador-port-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/estibador-portuario\/\" class=\"_self\" target=\"_self\" >Estibador Portuario<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/estilistadecortes\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2019\/10\/estilista-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/estilistadecortes\/\" class=\"_self\" target=\"_self\" >Estilista de Cortes de Cabello para Dama<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/gestor-ambiental\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2025\/04\/gestor-ambiental-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/gestor-ambiental\/\" class=\"_self\" target=\"_self\" >Gestor ambiental<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/jardinero\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2023\/04\/jardinero-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/jardinero\/\" class=\"_self\" target=\"_self\" >Implantaci\u00f3n y mantenimiento de jardines y zonas verdes (jardinero)<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalacion-minisplit\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2023\/04\/minisplit-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalacion-minisplit\/\" class=\"_self\" target=\"_self\" >Instalaci\u00f3n de aire acondicionado tipo dividido (mini split\/inverter)<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalacionesgas\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2023\/08\/instalacion-gas-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalacionesgas\/\" class=\"_self\" target=\"_self\" >Instalaci\u00f3n de redes de gas propano comerciales y domiciliares<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalacion-vrf\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2023\/04\/ac-vrf-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalacion-vrf\/\" class=\"_self\" target=\"_self\" >Instalaci\u00f3n y mantenimiento de aire acondicionado VRF (flujo de refrigerante variable)<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalacion-y-mantenimiento-de-circuitos-electricos-trifasicos\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2026\/05\/cicuitos-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalacion-y-mantenimiento-de-circuitos-electricos-trifasicos\/\" class=\"_self\" target=\"_self\" >Instalaci\u00f3n y mantenimiento de circuitos el\u00e9ctricos trif\u00e1sicos<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalacion-y-mantenimiento-de-maquinas-electricas-rotativas-trifasicas\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2026\/05\/maquinarot-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalacion-y-mantenimiento-de-maquinas-electricas-rotativas-trifasicas\/\" class=\"_self\" target=\"_self\" >Instalaci\u00f3n y mantenimiento de m\u00e1quinas el\u00e9ctricas rotativas trif\u00e1sicas<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalacion-maquinas-estacionarias\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2026\/05\/maquina-trif-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalacion-maquinas-estacionarias\/\" class=\"_self\" target=\"_self\" >Instalaci\u00f3n y mantenimiento de m\u00e1quinas estacionarias (transformadores) trif\u00e1sicas<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalador-de-andamios-de-grapa-y-tubo\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2024\/03\/andamio-tubo-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalador-de-andamios-de-grapa-y-tubo\/\" class=\"_self\" target=\"_self\" >Instalador de andamios de grapa y tubo<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalador-de-andamios-de-marco-y-cruceta-tubulares\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2024\/03\/instalacion-andamios-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalador-de-andamios-de-marco-y-cruceta-tubulares\/\" class=\"_self\" target=\"_self\" >Instalador de andamios de marco y cruceta (tubulares)<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalador-de-andamios-multidireccionales\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2024\/03\/instalacion-andamios-multi-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalador-de-andamios-multidireccionales\/\" class=\"_self\" target=\"_self\" >Instalador de andamios multidireccionales<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalador-de-artefactos-sanitarios\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2024\/03\/instalacion-sanitarios-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalador-de-artefactos-sanitarios\/\" class=\"_self\" target=\"_self\" >Instalador de artefactos sanitarios<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalador-cielosfalsos\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2026\/03\/instalador-cielos-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalador-cielosfalsos\/\" class=\"_self\" target=\"_self\" >Instalador de cielos falsos armados y suspendidos<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalador-de-circuitos-electricos-para-residencias-y-comercios\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2024\/03\/instalacion-circuitos-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalador-de-circuitos-electricos-para-residencias-y-comercios\/\" class=\"_self\" target=\"_self\" >Instalador de circuitos el\u00e9ctricos para residencias y comercios<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalador-fachaletas\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2023\/04\/instalador-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalador-fachaletas\/\" class=\"_self\" target=\"_self\" >Instalador de fachaletas<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instaladorpisos\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2023\/08\/instalador-piso-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instaladorpisos\/\" class=\"_self\" target=\"_self\" >Instalador de pisos cer\u00e1micos y azulejos<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalador-de-sistema-fotovoltaicos-paneles-solares\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2024\/03\/instalacion-sistemasfotov-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalador-de-sistema-fotovoltaicos-paneles-solares\/\" class=\"_self\" target=\"_self\" >Instalador de sistema fotovoltaicos (paneles solares)<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalador-tabiques-yeso\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2023\/04\/instalador-tyeso-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalador-tabiques-yeso\/\" class=\"_self\" target=\"_self\" >Instalador de tabiques de yeso<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalador-de-techos-inclinados-de-lamina\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2024\/03\/instalacion-laminas-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalador-de-techos-inclinados-de-lamina\/\" class=\"_self\" target=\"_self\" >Instalador de techos inclinados de l\u00e1mina<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalador-de-ventanas-de-pvc\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2024\/03\/instalador-pvc-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalador-de-ventanas-de-pvc\/\" class=\"_self\" target=\"_self\" >Instalador de ventanas de PVC<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instrumentista-industrial\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2026\/05\/instrumentista-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instrumentista-industrial\/\" class=\"_self\" target=\"_self\" >Instrumentista industrial<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/levantadormuros\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2023\/08\/levantadormuros-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/levantadormuros\/\" class=\"_self\" target=\"_self\" >Levantador de muros de mamposter\u00eda reforzados y no reforzados<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/maestro-de-obra\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2026\/05\/maestroobra-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/maestro-de-obra\/\" class=\"_self\" target=\"_self\" >Maestro de obra<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/manicura-spa\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2023\/04\/manicura-spa-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/manicura-spa\/\" class=\"_self\" target=\"_self\" >Manicura y pedicura tipo spa<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/mantenimiento-de-motores-diesel\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2024\/03\/mantenimiento-motordiesel-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/mantenimiento-de-motores-diesel\/\" class=\"_self\" target=\"_self\" >Mantenimiento de motores di\u00e9sel<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/mantenimiento-y-reparacion-de-aire-acondicionado-de-automoviles\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2024\/03\/reparacion-ac-auto-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/mantenimiento-y-reparacion-de-aire-acondicionado-de-automoviles\/\" class=\"_self\" target=\"_self\" >Mantenimiento y reparaci\u00f3n de aire acondicionado de autom\u00f3viles<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/mantenimiento-chiller\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2023\/04\/chiller-ac-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/mantenimiento-chiller\/\" class=\"_self\" target=\"_self\" >Mantenimiento y reparaci\u00f3n de Chiller (Unidades enfriadoras de l\u00edquidos o generadora de agua helada)<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/reparacion-cuartosfrios\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2023\/04\/reparacion-cuarto-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/reparacion-cuartosfrios\/\" class=\"_self\" target=\"_self\" >Mantenimiento y reparaci\u00f3n de cuartos fr\u00edos de media y baja temperatura<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/mante-refrigeracion\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2023\/04\/refrigeracion-terrestre-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/mante-refrigeracion\/\" class=\"_self\" target=\"_self\" >Mantenimiento y reparaci\u00f3n de equipos de refrigeraci\u00f3n de transporte terrestre<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/maquillista-eventos\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2019\/10\/maquillista-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/maquillista-eventos\/\" class=\"_self\" target=\"_self\" >Maquillista para Eventos Sociales<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/maquillista-para-eventos-sociales-en-linea\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2019\/10\/maquillista-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/maquillista-para-eventos-sociales-en-linea\/\" class=\"_self\" target=\"_self\" >Maquillista para Eventos Sociales (en l\u00ednea)<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/masaje-reductor\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2023\/04\/masaje-red-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/masaje-reductor\/\" class=\"_self\" target=\"_self\" >Masaje Reductor<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/masaje-presion\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2023\/04\/masaje-presion-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/masaje-presion\/\" class=\"_self\" target=\"_self\" >Masaje relajante manual por presi\u00f3n<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/mecanico-fresador\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2026\/05\/mecanicofres-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/mecanico-fresador\/\" class=\"_self\" target=\"_self\" >Mec\u00e1nico Fresador<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/mecanico-tornero\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2026\/05\/mecanico_tornero-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/mecanico-tornero\/\" class=\"_self\" target=\"_self\" >Mec\u00e1nico Tornero<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/mesero-rest\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2023\/04\/mesero-rest-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/mesero-rest\/\" class=\"_self\" target=\"_self\" >Mesero de Restaurante<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/colorista\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2023\/04\/colorista-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/colorista\/\" class=\"_self\" target=\"_self\" >Modificaci\u00f3n de la coloraci\u00f3n del cabello (colorista)<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/montaje-desmontaje-encofrados\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2023\/07\/encofrado-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/montaje-desmontaje-encofrados\/\" class=\"_self\" target=\"_self\" >Montaje y desmontaje de encofrados<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/operacion-collaretera\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2019\/10\/operacion-collaretera-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/operacion-collaretera\/\" class=\"_self\" target=\"_self\" >Operaci\u00f3n de M\u00e1quina de Coser Industrial Collaretera<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/operacion-overlock\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2019\/10\/operacion-overlock-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/operacion-overlock\/\" class=\"_self\" target=\"_self\" >Operaci\u00f3n de M\u00e1quina de Coser Industrial Overlock<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/operacion-plana\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2019\/10\/operacion-plana-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/operacion-plana\/\" class=\"_self\" target=\"_self\" >Operaci\u00f3n de M\u00e1quina de Coser Industrial Plana<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/operador-cf\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2023\/04\/operador-carga-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/operador-cf\/\" class=\"_self\" target=\"_self\" >Operador de cargador frontal<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/operador-de-grua-a-bordo-de-buque\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2026\/04\/operador-grua-buque-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/operador-de-grua-a-bordo-de-buque\/\" class=\"_self\" target=\"_self\" >Operador de gr\u00faa a bordo de buque<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/operador-motosierra\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2023\/08\/operador-motosierra-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/operador-motosierra\/\" class=\"_self\" target=\"_self\" >Operador de Motosierra<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/ordenador-de-ganado-vacuno-y-caprino\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2026\/04\/ordeniador-ganado-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/ordenador-de-ganado-vacuno-y-caprino\/\" class=\"_self\" target=\"_self\" >Orde\u00f1ador de ganado vacuno y caprino<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/organizador-eventos\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2025\/04\/organizador-eventos-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/organizador-eventos\/\" class=\"_self\" target=\"_self\" >Organizador de eventos sociales<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/parrillero\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2026\/05\/parillero-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/parrillero\/\" class=\"_self\" target=\"_self\" >Parrillero<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/piloto-de-transporte-de-productos-derivados-del-petroleo\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2026\/05\/piloto-transporte-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/piloto-de-transporte-de-productos-derivados-del-petroleo\/\" class=\"_self\" target=\"_self\" >Piloto de transporte de productos derivados del petr\u00f3leo<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/promotor-desarrollo\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2025\/04\/promotor-desarrollo-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/promotor-desarrollo\/\" class=\"_self\" target=\"_self\" >Promotor de desarrollo comunitario<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/recepcionista-hotel\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2023\/04\/recepcionista-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/recepcionista-hotel\/\" class=\"_self\" target=\"_self\" >Recepcionista de hotel<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/reparacion-refridom\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2023\/04\/reparacion-refridom-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/reparacion-refridom\/\" class=\"_self\" target=\"_self\" >Reparaci\u00f3n de refrigeradoras de uso dom\u00e9stico<\/a><\/h5><\/div><\/div>\n<div class=\"col-md-2 col-sm-6 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/supervisor-de-habitaciones-areas-nobles-y-de-servicio\/\" class=\"_self pt-cv-href-thumbnail pt-cv-thumb-default\" target=\"_self\" ><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2024\/03\/supervisor-habi-300x75.jpg\" class=\"pt-cv-thumbnail\" alt=\"\" \/><\/a>\n<h5 class=\"pt-cv-title\"><a href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/supervisor-de-habitaciones-areas-nobles-y-de-servicio\/\" class=\"_self\" target=\"_self\" >Supervisor de habitaciones, \u00e1reas nobles y de servicio<\/a><\/h5><\/div><\/div><\/div><\/div><\/div><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":1867,"parent":214,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-1864","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Instalador de andamios de grapa y tubo - Certificaci\u00f3n Laboral INTECAP<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalador-de-andamios-de-grapa-y-tubo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Instalador de andamios de grapa y tubo - Certificaci\u00f3n Laboral INTECAP\" \/>\n<meta property=\"og:url\" content=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalador-de-andamios-de-grapa-y-tubo\/\" \/>\n<meta property=\"og:site_name\" content=\"Certificaci\u00f3n Laboral INTECAP\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-23T18:39:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2024\/03\/andamio-tubo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/intecap.edu.gt\\\/certificacionlaboral\\\/certificacionfuncional\\\/instalador-de-andamios-de-grapa-y-tubo\\\/\",\"url\":\"https:\\\/\\\/intecap.edu.gt\\\/certificacionlaboral\\\/certificacionfuncional\\\/instalador-de-andamios-de-grapa-y-tubo\\\/\",\"name\":\"Instalador de andamios de grapa y tubo - Certificaci\u00f3n Laboral INTECAP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/intecap.edu.gt\\\/certificacionlaboral\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/intecap.edu.gt\\\/certificacionlaboral\\\/certificacionfuncional\\\/instalador-de-andamios-de-grapa-y-tubo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/intecap.edu.gt\\\/certificacionlaboral\\\/certificacionfuncional\\\/instalador-de-andamios-de-grapa-y-tubo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/intecap.edu.gt\\\/certificacionlaboral\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/andamio-tubo.jpg\",\"datePublished\":\"2024-03-13T21:01:41+00:00\",\"dateModified\":\"2026-03-23T18:39:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/intecap.edu.gt\\\/certificacionlaboral\\\/certificacionfuncional\\\/instalador-de-andamios-de-grapa-y-tubo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/intecap.edu.gt\\\/certificacionlaboral\\\/certificacionfuncional\\\/instalador-de-andamios-de-grapa-y-tubo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/intecap.edu.gt\\\/certificacionlaboral\\\/certificacionfuncional\\\/instalador-de-andamios-de-grapa-y-tubo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/intecap.edu.gt\\\/certificacionlaboral\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/andamio-tubo.jpg\",\"contentUrl\":\"https:\\\/\\\/intecap.edu.gt\\\/certificacionlaboral\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/andamio-tubo.jpg\",\"width\":1400,\"height\":350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/intecap.edu.gt\\\/certificacionlaboral\\\/certificacionfuncional\\\/instalador-de-andamios-de-grapa-y-tubo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/intecap.edu.gt\\\/certificacionlaboral\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Certificaci\u00f3n Funcional\",\"item\":\"https:\\\/\\\/intecap.edu.gt\\\/certificacionlaboral\\\/certificacionfuncional\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Instalador de andamios de grapa y tubo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/intecap.edu.gt\\\/certificacionlaboral\\\/#website\",\"url\":\"https:\\\/\\\/intecap.edu.gt\\\/certificacionlaboral\\\/\",\"name\":\"Certificaci\u00f3n Laboral INTECAP\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/intecap.edu.gt\\\/certificacionlaboral\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/intecap.edu.gt\\\/certificacionlaboral\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/intecap.edu.gt\\\/certificacionlaboral\\\/#organization\",\"name\":\"INTECAP\",\"url\":\"https:\\\/\\\/intecap.edu.gt\\\/certificacionlaboral\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/intecap.edu.gt\\\/certificacionlaboral\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/intecap.edu.gt\\\/certificacionlaboral\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Logo-Gris-Intecap-scaled.png\",\"contentUrl\":\"https:\\\/\\\/intecap.edu.gt\\\/certificacionlaboral\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Logo-Gris-Intecap-scaled.png\",\"width\":2560,\"height\":1157,\"caption\":\"INTECAP\"},\"image\":{\"@id\":\"https:\\\/\\\/intecap.edu.gt\\\/certificacionlaboral\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Instalador de andamios de grapa y tubo - Certificaci\u00f3n Laboral INTECAP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalador-de-andamios-de-grapa-y-tubo\/","og_locale":"es_ES","og_type":"article","og_title":"Instalador de andamios de grapa y tubo - Certificaci\u00f3n Laboral INTECAP","og_url":"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalador-de-andamios-de-grapa-y-tubo\/","og_site_name":"Certificaci\u00f3n Laboral INTECAP","article_modified_time":"2026-03-23T18:39:43+00:00","og_image":[{"width":1400,"height":350,"url":"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2024\/03\/andamio-tubo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalador-de-andamios-de-grapa-y-tubo\/","url":"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalador-de-andamios-de-grapa-y-tubo\/","name":"Instalador de andamios de grapa y tubo - Certificaci\u00f3n Laboral INTECAP","isPartOf":{"@id":"https:\/\/intecap.edu.gt\/certificacionlaboral\/#website"},"primaryImageOfPage":{"@id":"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalador-de-andamios-de-grapa-y-tubo\/#primaryimage"},"image":{"@id":"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalador-de-andamios-de-grapa-y-tubo\/#primaryimage"},"thumbnailUrl":"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2024\/03\/andamio-tubo.jpg","datePublished":"2024-03-13T21:01:41+00:00","dateModified":"2026-03-23T18:39:43+00:00","breadcrumb":{"@id":"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalador-de-andamios-de-grapa-y-tubo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalador-de-andamios-de-grapa-y-tubo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalador-de-andamios-de-grapa-y-tubo\/#primaryimage","url":"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2024\/03\/andamio-tubo.jpg","contentUrl":"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2024\/03\/andamio-tubo.jpg","width":1400,"height":350},{"@type":"BreadcrumbList","@id":"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/instalador-de-andamios-de-grapa-y-tubo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/intecap.edu.gt\/certificacionlaboral\/"},{"@type":"ListItem","position":2,"name":"Certificaci\u00f3n Funcional","item":"https:\/\/intecap.edu.gt\/certificacionlaboral\/certificacionfuncional\/"},{"@type":"ListItem","position":3,"name":"Instalador de andamios de grapa y tubo"}]},{"@type":"WebSite","@id":"https:\/\/intecap.edu.gt\/certificacionlaboral\/#website","url":"https:\/\/intecap.edu.gt\/certificacionlaboral\/","name":"Certificaci\u00f3n Laboral INTECAP","description":"","publisher":{"@id":"https:\/\/intecap.edu.gt\/certificacionlaboral\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/intecap.edu.gt\/certificacionlaboral\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/intecap.edu.gt\/certificacionlaboral\/#organization","name":"INTECAP","url":"https:\/\/intecap.edu.gt\/certificacionlaboral\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/intecap.edu.gt\/certificacionlaboral\/#\/schema\/logo\/image\/","url":"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2026\/02\/Logo-Gris-Intecap-scaled.png","contentUrl":"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-content\/uploads\/2026\/02\/Logo-Gris-Intecap-scaled.png","width":2560,"height":1157,"caption":"INTECAP"},"image":{"@id":"https:\/\/intecap.edu.gt\/certificacionlaboral\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-json\/wp\/v2\/pages\/1864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-json\/wp\/v2\/comments?post=1864"}],"version-history":[{"count":7,"href":"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-json\/wp\/v2\/pages\/1864\/revisions"}],"predecessor-version":[{"id":3009,"href":"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-json\/wp\/v2\/pages\/1864\/revisions\/3009"}],"up":[{"embeddable":true,"href":"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-json\/wp\/v2\/pages\/214"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-json\/wp\/v2\/media\/1867"}],"wp:attachment":[{"href":"https:\/\/intecap.edu.gt\/certificacionlaboral\/wp-json\/wp\/v2\/media?parent=1864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}